{"id":936,"date":"2023-06-14T15:27:36","date_gmt":"2023-06-14T13:27:36","guid":{"rendered":"https:\/\/ecosystemadotpro.wordpress.com\/?p=936"},"modified":"2023-06-14T15:27:37","modified_gmt":"2023-06-14T13:27:37","slug":"les-chitons-leptochiton-sp-polyplacophora","status":"publish","type":"post","link":"https:\/\/ecosystema.fr\/index.php\/2023\/06\/14\/les-chitons-leptochiton-sp-polyplacophora\/","title":{"rendered":"Les Chitons : Leptochiton sp. (Polyplacophora)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-938\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2007\/10\/gaby_ar_braz_63.jpg\" alt=\"Gaby_AR_BRAZ_63\" width=\"1154\" height=\"866\" \/><\/p>\n<p>C\u2019est \u00e0 l\u2019occasion d\u2019une sortie littoral, le 30 septembre 2007, avec Nathalie de la SEPNB (Maison du littoral BP 26 CEDEX 171, 29910 TREGUNC) et dans le cadre de <b>l\u2019\u00e9cole de la nature <\/b>(<a href=\"http:\/\/bretagnevivante.asso.free.fr\/EcoleNature.html\">http:\/\/bretagnevivante.asso.free.fr\/EcoleNature.html<\/a>), que nous avons observ\u00e9 cet animal sous un caillou.<\/p>\n<hr \/>\n<p>Il s\u2019agit de deux <b><i>Leptochiton sp. (Polyplacophora)<\/i><\/b><\/p>\n<hr \/>\n<p><strong>G\u00e9n\u00e9ralit\u00e9s<\/strong><\/p>\n<p>Les Chitons repr\u00e9sentent 860 esp\u00e8ces de la classe des <b>Polyplacophores<\/b>. Ils rampent lentement gr\u00e2ce \u00e0 leur pied musculeux. Les esp\u00e8ces les plus r\u00e9pandues se trouvent dans la <b>zone intertidale*<\/b>, sur ou dans les rochers, mais certaines esp\u00e8ces ont \u00e9t\u00e9 trouv\u00e9es \u00e0 4000 m de profondeur. Les plaques s\u00e9par\u00e9es sont parfois appel\u00e9es \u00ab\u00a0coquilles papillons\u00a0\u00bb.<\/p>\n<p>* L&rsquo;estran est la partie du littoral situ\u00e9e entre les niveaux connus des plus hautes et des plus basses mers. On utilise aussi pour le d\u00e9signer le terme \u00ab zone de marnage \u00bb ou l&rsquo;<b>anglicisme \u00ab zone intertidale \u00bb (de l&rsquo;anglais tidal signifiant \u00ab relatif \u00e0 la mar\u00e9e \u00bb) <\/b>; en termes administratifs et juridiques, on emploie aussi l&rsquo;expression \u00ab\u00a0zone de balancement des mar\u00e9es\u00a0\u00bb.<\/p>\n<p>L&rsquo;estran est donc (au moins en partie) recouvert lors des pleines mers et d\u00e9couvert lors des basses mers. La dur\u00e9e d&rsquo;exondation (important pour l&rsquo;installation des organismes qui y sont inf\u00e9od\u00e9s) des diff\u00e9rentes parties de l&rsquo;estran d\u00e9pend de leurs emplacements par rapport au niveau moyen de la mer et du nombre (deux sur les c\u00f4tes atlantiques de la France mais une dans certaines r\u00e9gions du globe) des mar\u00e9es par jour.<\/p>\n<hr \/>\n<p><strong>Structure<\/strong><\/p>\n<p>La coquille dorsale qui prot\u00e8ge les chitons est constitu\u00e9e d&rsquo;aragonite, multicolore, d\u00e9cor\u00e9e de motifs, lisse ou sculpt\u00e9e. La coquille est divis\u00e9e en huit <b>plaques articul\u00e9es<\/b> (\u00e9galement appel\u00e9es valves) envelopp\u00e9es dans la ceinture musculaire qui entoure le corps du chiton. Cette disposition permet aux chitons de se rouler en boule en cas de danger et de s&rsquo;accrocher sur des surfaces irr\u00e9guli\u00e8res. <b>La ceinture musculaire et souvent orn\u00e9e de spicules, de brins, de touffes de \u00ab\u00a0poils\u00a0\u00bb ou de dessins en \u00e9cailles de serpents<\/b>. La plus grande partie du corps est un pied similaire \u00e0 celui des escargots, mais ni t\u00eate ni autre partie molle au-del\u00e0 de la ceinture musculaire ne sont visibles depuis le dos de l&rsquo;animal. Entre le corps et la ceinture, il y a la cavit\u00e9 pall\u00e9ale, connect\u00e9e \u00e0 l&rsquo;ext\u00e9rieur par des canaux aquif\u00e8res. Le canal lat\u00e9ral est le canal aquif\u00e8re entrant. Celui qui est attach\u00e9 \u00e0 l&rsquo;anus est le canal aquif\u00e8re sortant. Les branchies pendent dans la cavit\u00e9 pall\u00e9ale, rarement pr\u00e8s de l&rsquo;anus. La t\u00eate poss\u00e8de une bouche dans laquelle se trouve une sorte de langue appel\u00e9e <b>radula<\/b>, qui poss\u00e8de de nombreuses rang\u00e9es de 17 dents chacune. Les dents sont enduites de magn\u00e9tite, un min\u00e9ral ferreux qui renforce les dents. La radula a pour r\u00f4le de racler des algues microscopiques pos\u00e9es sur le substrat.<\/p>\n<blockquote><p>Le nom des Chitons vient du grec <i>chit\u014dn<\/i>, qui signifie \u00ab\u00a0tunique\u00a0\u00bb. Il est \u00e9galement \u00e0 l&rsquo;origine du mot chitine. Le terme de Polyplacophores vient des mots grecs <i>poly<\/i>&#8211; (plusieurs), <i>plako<\/i>&#8211; (plaques), and &#8211;<i>phoros<\/i> (transport).<\/p><\/blockquote>\n<p>Les Chitons furent \u00e9tudi\u00e9s pour la premi\u00e8re fois par Linn\u00e9 en 1758. Depuis sa description des quatre premi\u00e8res esp\u00e8ces, les Chitons ont \u00e9t\u00e9 class\u00e9s diversement. Ils ont \u00e9t\u00e9 appel\u00e9s les Cyclobranches (\u00ab\u00a0bras arrondi\u00a0\u00bb) au d\u00e9but du XIXe si\u00e8cle puis group\u00e9s alors avec les Aplacophores dans le sous-phylum des Amphineures en 1876. <b>La classe des Polyplacophores a \u00e9t\u00e9 introduite par J. E. Gray en 1821<\/b>.<\/p>\n<hr \/>\n<p><strong>Mode de vie<\/strong><\/p>\n<p>Les Chitons mangent des Algues, des Bryozoaires, des Diatom\u00e9es et parfois des Bact\u00e9ries en raclant le substrat rocheux \u00e0 l&rsquo;aide de leur radula bien d\u00e9velopp\u00e9e.<\/p>\n<p>Certaines esp\u00e8ces ont une ceinture \u00e9largie \u00e0 l&rsquo;avant et se fixent sur d&rsquo;autres animaux. Certains chitons ont un comportement casanier, retournant au m\u00eame endroit le jour et se d\u00e9pla\u00e7ant pour se nourrir la nuit.<\/p>\n<p>Leurs pr\u00e9dateurs sont les mouettes, les \u00e9toiles de mer, les crabes et les an\u00e9mones de mer.<\/p>\n<hr \/>\n<p><strong>D\u00e9termination des individus photographi\u00e9s&#8230;<\/strong><\/p>\n<p>Aidez moi SVP ! (mettez vos commentaires).<\/p>\n<p>Toutefois, on peut dire qu\u2019il existe plusieurs esp\u00e8ces de chitons sur les c\u00f4tes fran\u00e7aises. <b>Les diff\u00e9rencier est souvent affaire de sp\u00e9cialistes<\/b>. Il faut parfois aller jusqu&rsquo;\u00e0 retirer des plaques pour examiner en d\u00e9tail l&rsquo;animal et identifier l&rsquo;esp\u00e8ce avec certitude. Ces animaux pr\u00e9sentent tous la m\u00eame forme ovale, et <b>la couleur ne peut pas \u00eatre prise en compte comme crit\u00e8re d&rsquo;identification<\/b>. La taille du chiton peut parfois permettre d&rsquo;\u00e9carter telle ou telle esp\u00e8ce. Le bord du manteau s\u00e9cr\u00e8te par ailleurs des spicules calcaires, et porte parfois des petites touffes de soies \u00e9pineuses. Ces diff\u00e9rents crit\u00e8res peuvent aider \u00e0 la d\u00e9termination du genre, voire de l&rsquo;esp\u00e8ce.<\/p>\n<hr \/>\n<p>Citons :<\/p>\n<p><i>Lepidochitona cinerea<\/i> (Chiton cendr\u00e9 ou chiton gris), l&rsquo;esp\u00e8ce la plus commune sur les c\u00f4tes fran\u00e7aises. De couleur plus terne (gris \u00e0 brun cendre), cette esp\u00e8ce est \u00e9galement plus petite (1 \u00e0 2 cm en g\u00e9n\u00e9ral).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-939\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2007\/10\/gaby_ar_braz_64.jpg\" alt=\"Gaby_AR_BRAZ_64\" width=\"1154\" height=\"866\" \/><\/p>\n<p style=\"text-align:center;\">Clich\u00e9 2 (GLB) : <i>Lepidochitona cf. cinerea <\/i>(\u00e0 confirmer)<\/p>\n<hr \/>\n<p>A ne pas confondre&#8230;<\/p>\n<p>Le chiton est aussi un <b>v\u00eatement de la Gr\u00e8ce antique<\/b>. C&rsquo;est une tunique port\u00e9e par les hommes comme par les femmes. D&rsquo;abord confectionn\u00e9 en laine dans les p\u00e9riodes les plus anciennes, il est ensuite fabriqu\u00e9 en lin et gagne alors en ampleur pour se porter avec une ceinture \u00e0 la taille.<\/p>\n<p>Chez les hommes, il peut couvrir la jambe jusqu&rsquo;\u00e0 mi-cuisse ou descendre jusqu&rsquo;au pied. Il peut \u00eatre orn\u00e9 de dessins g\u00e9om\u00e9triques pour les jours de f\u00eate. Il se peut se porter avec un <i>pallium<\/i> (sorte de manteau).<\/p>\n<p>Chez les femmes, il se porte long. On parle parfois de chiton ionique. Avec l&rsquo;apparition du lin, il remplace progressivement le <i>p\u00e9plos<\/i> dont il se diff\u00e9rencie car il ne retombe pas en plis sur la poitrine et se porte bouffant \u00e0 la taille gr\u00e2ce \u00e0 une ceinture.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong>Sources :<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/fr.wikipedia.org\/wiki\/Chiton\">http:\/\/fr.wikipedia.org\/wiki\/Chiton<\/a><\/li>\n<\/ul>\n<p><b>Clich\u00e9s<\/b> :\u00a0Gaby AR BRAZ &#8211; APN Canon G9\u00a0&#8211; Ecosystema.fr\u00a0\u00a9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est \u00e0 l\u2019occasion d\u2019une sortie littoral, le 30 septembre 2007, avec Nathalie de la SEPNB (Maison du littoral BP 26 CEDEX 171, 29910 TREGUNC) et dans le cadre de l\u2019\u00e9cole de la nature (http:\/\/bretagnevivante.asso.free.fr\/EcoleNature.html), que nous avons observ\u00e9 cet animal sous un caillou. Il s\u2019agit de deux Leptochiton sp. (Polyplacophora) G\u00e9n\u00e9ralit\u00e9s Les Chitons repr\u00e9sentent 860&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[85],"class_list":["post-936","post","type-post","status-publish","format-standard","hentry","category-faune-oceanographie","tag-littoral"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/comments?post=936"}],"version-history":[{"count":1,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/936\/revisions"}],"predecessor-version":[{"id":2343,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/936\/revisions\/2343"}],"wp:attachment":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/media?parent=936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/categories?post=936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/tags?post=936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}