{"id":44,"date":"2023-06-14T15:26:56","date_gmt":"2023-06-14T13:26:56","guid":{"rendered":"https:\/\/ecosystemadotpro.wordpress.com\/?p=44"},"modified":"2023-06-14T15:44:51","modified_gmt":"2023-06-14T13:44:51","slug":"anemone-pulsatille","status":"publish","type":"post","link":"https:\/\/ecosystema.fr\/index.php\/2023\/06\/14\/anemone-pulsatille\/","title":{"rendered":"An\u00e9mone pulsatille"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2016\/04\/14-07-2009-21-48-44_0032.jpg\" class=\"alignnone size-full wp-image-45\" alt=\"14-07-2009 21-48-44_0032\" width=\"1024\" height=\"696\" srcset=\"https:\/\/ecosystema.fr\/wp-content\/uploads\/2016\/04\/14-07-2009-21-48-44_0032.jpg 1024w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2016\/04\/14-07-2009-21-48-44_0032-300x204.jpg 300w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2016\/04\/14-07-2009-21-48-44_0032-768x522.jpg 768w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2016\/04\/14-07-2009-21-48-44_0032-809x550.jpg 809w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>C\u2019est lors d\u2019une reconnaissance de terrain dans le sud-est de la Haute-Normandie (le PNR du <i>Vexin Fran\u00e7ais<\/i>), que j\u2019ai visit\u00e9 les <b>coteaux des Andelys<\/b> pr\u00e8s du ch\u00e2teau gaillard.<\/p>\n<hr>\n<p>\u00c0 cette occasion, j&rsquo;ai observ\u00e9 cette jolie fleur (aussi utilis\u00e9 en horticulture).<\/p>\n<blockquote><p>Il s&rsquo;agit de <b><i>Pulsatilla vulgaris<\/i> Mill.<\/b> (= <i>Anemone pulsatilla<\/i> L.), dite aussi an\u00e9mone pulsatille, pulsatille vulgaire, coquerelle, coquelourde, fleur-de-P\u00e2ques, herbe-au-vent, fleur-aux-dames et j&rsquo;en passe.<\/p>\n<\/blockquote>\n<p>Bref pour plus de clart\u00e9, il s&rsquo;agit de <i>Pulsatilla vulagaris<\/i> ! ^^<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2010\/05\/gabyarbraz_021.jpg?w=680\" class=\"aligncenter wp-image-265\" alt=\"Pulsatilla vulgaris, C\u00f4te de l'Estr\u00e9e (27), 23\/04\/00\" width=\"393\" height=\"584\"><\/p>\n<p style=\"text-align: center\"><b>Clich\u00e9s<\/b> :&nbsp;Gaby AR BRAZ &#8211; Velvia 50 iso&nbsp;&#8211; Ecosystema.fr&nbsp;\u00a9<\/p>\n<p>Observ\u00e9 \u00e0 la mi\u2014avril, elle fleurit de mars \u00e0 mai. C&rsquo;est une h\u00e9micryptophyte, mesurant de 10 \u00e0 (rarement) 30 cm.<\/p>\n<p>\u00c9cologiquement, c&rsquo;est une esp\u00e8ce \u00ab prairiale \u00bb, x\u00e9rophile, thermophile, calcicole.<\/p>\n<p>On peut l&rsquo;observer (comme ici) sur les pelouses calcicoles, coteaux (ici des Andelys) ; mais aussi sur les talus, bermes.<\/p>\n<blockquote><p>Phytosociologiquement elle fait partie du cort\u00e8ge du <b><i>Seslerio-Mesobromenion erecti<\/i><\/b>, correspondant \u00e0 une v\u00e9g\u00e9tation v\u00e9g\u00e9tation vivace de pelouses oligotrophe, calcicole, sur sols plus ou moins profonds \u00e0 nette tendance&nbsp; m\u00e9so-x\u00e9rophile.<\/p>\n<\/blockquote>\n<p>On peut la trouver associ\u00e9e \u00e0 <i>Euphorbia seguierana, Globularia punctata, Gymnadenia odoratissima, Sesleria albicans, Teucrium montanum, Aster linosyris<\/i>, etc.<\/p>\n<p>Concernant sa chorologie, c\u2019est une m\u00e9dio-europ\u00e9enne (ouest).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2010\/05\/gabyarbraz_142.jpg\" class=\"alignnone size-full wp-image-279\" alt=\"Coteaux calcaires de la Roche-Guyon (95), 23\/06\/02\" width=\"1024\" height=\"696\"><\/p>\n<p style=\"text-align: center\"><b>Clich\u00e9s<\/b> :&nbsp;Gaby AR BRAZ &#8211; Velvia 50 iso&nbsp;&#8211; Ecosystema.fr&nbsp;\u00a9<\/p>\n<p>Son habitat : coteau calcaricole des Andelys (La C\u00f4te Saint-Jacques), en Haute-Normandie (27).<\/p>\n<p><span style=\"text-decoration: underline\">R\u00e9flexions et perspectives :<\/span><\/p>\n<p>Courriel adress\u00e9 au CS de la R.N.N. des coteaux de la seine (78) le 14\/05\/2013 (CS de la RNN : Floche Sebastien du CBN de Paris, dont je n&rsquo;ai eu aucune r\u00e9ponse).<\/p>\n<hr>\n<p>Je pr\u00e9cise que j&rsquo;ai r\u00e9alis\u00e9 la cartographie g\u00e9obotanique de la RNN \u00e0 la demande P.N.R. du Vexin Fran\u00e7ais.<br \/>\nAinsi, je me suis rapproch\u00e9 de lui (au titre d&rsquo;expert ?) pour savoir ce qu&rsquo;il envisageait suite \u00e0 l&rsquo;\u00e9tude r\u00e9alis\u00e9e par moi-m\u00eame et fortement simplifi\u00e9e \u00e0 la demande du commanditaire sur une <strong>association<\/strong> qui me perturbe un peu.<\/p>\n<p>Il s&rsquo;agit du <strong><em>Pulsatillo vulgaris \u2013 Seslerietum albicantis<\/em><\/strong> d\u00e9crit par Vincent BOULLET en 1986. Elle est inform\u00e9e comme \u00e9tant circonscrite en aval de Vernon, or je suis presque convaincu, qu&rsquo;elle est pr\u00e9sente sur la r\u00e9serve des coteaux de la Seine (CODE : RNN170 \/ FR3600170) car l&rsquo;unit\u00e9 synsyst\u00e9matique y est bien exprim\u00e9e.<\/p>\n<p>Je m&rsquo;adresse \u00e0 la communaut\u00e9 : pourriez-vous m&rsquo;informer sur vos r\u00e9flexions, prospections \u00e0 ce sujet ? entre&nbsp;gestionnaire, g\u00e9obotaniste, phytosociologue, etc.<br \/>\nTr\u00e8s sinc\u00e8rement.<\/p>\n<hr>\n<p><b>Clich\u00e9s<\/b>&nbsp;:&nbsp;Gaby AR BRAZ &#8211; APN Canon G9&nbsp;&#8211; Ecosystema.fr&nbsp;\u00a9<\/p>\n<hr>\n<p><b>Sources<\/b> :<\/p>\n<ul>\n<li>LAMBINON J. et al., Nouvelle flore de la Belgique, du Grand-Duch\u00e9 de Luxembourg, du Nord de la France et des R\u00e9gions voisines &#8211; 2004.<\/li>\n<li><b><a href=\"http:\/\/www.tela-botanica.org\">http:\/\/www.tela-botanica.org<\/a><\/b><\/li>\n<\/ul>\n<ul>\n<li><b><a href=\"http:\/\/office-tourisme.ville-andelys.fr\">http:\/\/office-tourisme.ville-andelys.fr<\/a><\/b><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est lors d\u2019une reconnaissance de terrain dans le sud-est de la Haute-Normandie (le PNR du Vexin Fran\u00e7ais), que j\u2019ai visit\u00e9 les coteaux des Andelys pr\u00e8s du ch\u00e2teau gaillard. \u00c0 cette occasion, j&rsquo;ai observ\u00e9 cette jolie fleur (aussi utilis\u00e9 en horticulture). Il s&rsquo;agit de Pulsatilla vulgaris Mill. (= Anemone pulsatilla L.), dite aussi an\u00e9mone pulsatille, pulsatille&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,27],"tags":[56],"class_list":["post-44","post","type-post","status-publish","format-standard","hentry","category-flore","category-pelouses-lisieres-et-forets-calcicoles","tag-coteaux-calcaires"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":2,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/44\/revisions"}],"predecessor-version":[{"id":3381,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/44\/revisions\/3381"}],"wp:attachment":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/media?parent=44"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/categories?post=44"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/tags?post=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}