{"id":28,"date":"2023-06-14T15:27:04","date_gmt":"2023-06-14T13:27:04","guid":{"rendered":"https:\/\/ecosystemadotpro.wordpress.com\/?p=28"},"modified":"2023-06-14T18:37:46","modified_gmt":"2023-06-14T16:37:46","slug":"rhizostoma-octopus-la-paisible","status":"publish","type":"post","link":"https:\/\/ecosystema.fr\/index.php\/2023\/06\/14\/rhizostoma-octopus-la-paisible\/","title":{"rendered":"Rhizostoma octopus, la paisible&#8230;t"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2010\/06\/meduse_2.jpg\" class=\"alignnone size-full wp-image-36\" alt=\"meduse_2\" width=\"1024\" height=\"711\"><\/p>\n<p>Voici une esp\u00e8ce observ\u00e9e dans le port de Douarnenez (29) en grand nombre. Il s&rsquo;agit de <i>Rhizostoma pulmo<\/i> (Macri, 1778) ; c&rsquo;est une \u00ab\u00a0M\u00e9duses vraies\u00a0\u00bb (Scyphozoaires) cosmopolite (Distribution Mondiale).<\/p>\n<p>On l&rsquo;appel aussi plus commun\u00e9ment \u00ab\u00a0Poumon de mer\u00a0\u00bb ou \u00ab\u00a0m\u00e9duse chou-fleur\u00a0\u00bb<\/p>\n<p>Pour l&rsquo;identifier, il s&rsquo;agit d&rsquo;une m\u00e9duse massive de grande taille (m\u00e9duse plut\u00f4t bleut\u00e9e et inoffensive), n&rsquo;ayant pas de de tentacules sur le bord de l&rsquo;ombrelle (elle n&rsquo;a pas de bouche capable d&rsquo;avaler de grosses proies) ; celle-ci \u00e9tant finement festonn\u00e9, dentel\u00e9 avec liser\u00e9 bleu.<\/p>\n<p>L&rsquo;esp\u00e8re pr\u00e9sent 4 bras buccaux soud\u00e9s et divis\u00e9s en 2, soit 8 lobes, avec une bouche transform\u00e9e en une structure aspirante et filtrante (Elle s\u00e9cr\u00e8te un mucus o\u00f9 s&rsquo;agglutinent de minuscules particules alimentaires dont elle se nourrit).<\/p>\n<p>Elle est de teinte principalement bleut\u00e9, mais aussi de teintes variables : blanc, jaune, orange, brun et violet.<\/p>\n<p><b>Concernant son biotope*<\/b><\/p>\n<blockquote><p>Le rhizostome est une m\u00e9duse planctonique, qui se d\u00e9place lentement en eau peu profonde (macroplancton g\u00e9latineux, necton) et qui abonde en g\u00e9n\u00e9ral en milieu c\u00f4tier. Elle est fr\u00e9quente dans les lagunes et les estuaires.<\/p>\n<\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2010\/06\/groupe_meduses.jpg\" class=\"alignright wp-image-33\" alt=\"groupe_meduses\" width=\"430\" height=\"578\"><\/p>\n<p>Pour la d\u00e9crire, on peut dire que le rhizostome est une grosse m\u00e9duse, massive (Elle peut mesurer jusqu&rsquo;\u00e0 1 m de diam\u00e8tre et peser 20 Kg !), dont l&rsquo;ombrelle en forme de cloche est frang\u00e9e de 80 \u00e0 100 lobes. Elle mesure en g\u00e9n\u00e9ral de 30 \u00e0 60 cm de diam\u00e8tre mais elle peut atteindre une taille de un m\u00e8tre. Les bords de l&rsquo;ombrelle sont finement dentel\u00e9s et pr\u00e9sentent un liser\u00e9 bleu ou mauve. Il n&rsquo;y a pas de tentacules. Sous l&rsquo;ombrelle le <em>manubrium<\/em> est form\u00e9 par la soudure des 4 bras buccaux, eux-m\u00eames divis\u00e9s en 2, soit 8 lobes. Chacun de ces 8 lobes se termine par 2 languettes transparentes. Cette fusion transforme la bouche en une structure aspirante et filtrante perc\u00e9e de nombreux petits trous: les ostioles. La couleur de la m\u00e9duse est tr\u00e8s variable: blanche, jaune, brune orang\u00e9e, verte, bleue ou mauve.<\/p>\n<blockquote><p>Parmi les esp\u00e8ces ressemblantes, citons <em>R. pulmo<\/em>, en effet <em>Rhizostoma octopus<\/em> (Linnaeus, 1788), serait en fait la vari\u00e9t\u00e9 atlantique, plus petite, de R. pulmo. Selon le principe d&rsquo;ant\u00e9riorit\u00e9, le nom valide de cette esp\u00e8ce est <em>Rhizostoma pulmo<\/em>, que Macri a d\u00e9crite 10 ans avant Linn\u00e9.<\/p>\n<\/blockquote>\n<p>Dans certains ouvrages ces 2 esp\u00e8ces sont pr\u00e9sent\u00e9es comme diff\u00e9rentes, <em>R. pulmo<\/em> \u00e9tant m\u00e9diterran\u00e9enne, <em>R. octopus<\/em> \u00e9tant nordique.<\/p>\n<p>Toutefois, dans la grande majorit\u00e9 des cas, ces deux \u00ab\u00a0esp\u00e8ces\u00a0\u00bb n&rsquo;en forment qu&rsquo;une, et les 2 noms sont reconnus comme synonymes ! donc pulmo ou octopus ? Noms scientifiques parfois utilis\u00e9s, mais non valides<\/p>\n<p><em>Rhizostoma octopus<\/em> (Linnaeus, 1788), qui serait en fait la vari\u00e9t\u00e9 atlantique de <em>R. pulmo<\/em>.<\/p>\n<p>Donc mon avis serait de l&rsquo;appeler <em>R. Pulmo<\/em>, mais pour une fois je ferais cadeau d&rsquo;une contrarit\u00e9 \u00e0 l&rsquo;\u00e9gard des maudit Breton ! ^^.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2010\/06\/rhizostoma_octopus-salaun.jpg\" class=\"alignleft wp-image-37\" alt=\"rhizostoma_octopus-salaun\" width=\"407\" height=\"659\"><\/p>\n<p>Depuis 20 ans (2010) que je plonge (aussi chasseur apn\u00e9iste depuis 1985) je semble observer un plus grand nombre de ces individu \u00e0 la p\u00e9riode de reproduction, qu&rsquo;en est-il vraiment ?<\/p>\n<blockquote><p><b>Pullulation de m\u00e9duses ou pas ?<\/b><\/p>\n<\/blockquote>\n<p>In \u00ab\u00a0<i>fr.academic.ru<\/i> \u00ab\u00a0, on peut lire la chose suivante :<\/p>\n<p>La pullulation de m\u00e9duses, prolif\u00e9ration de m\u00e9duses ou invasion de m\u00e9duses est un ph\u00e9nom\u00e8ne de multiplication massive de certaines esp\u00e8ces de m\u00e9duses (<strong>cnidaires libres<\/strong>). Il s&rsquo;agit d&rsquo;un type d&rsquo;invasion biologique.<\/p>\n<p>Ce ph\u00e9nom\u00e8ne, autrefois cyclique (avec 12 ans d&rsquo;intervalle, le ph\u00e9nom\u00e8ne durant de 4 \u00e0 6 ans) et relativement rare, est devenu beaucoup plus courant vers la fin du XXe si\u00e8cle, l&rsquo;action humaine (pollution, surp\u00eache, r\u00e9chauffement des eaux&#8230;) \u00e9tant probablement les raisons principales de ces pullulations. Toutefois, on pense qu&rsquo;il existe de nombreuses autres causes encore inconnues responsables de tels ph\u00e9nom\u00e8nes.<\/p>\n<p><b>Sommaire<\/b><\/p>\n<ol>\n<li>Description<\/li>\n<li>Cons\u00e9quences sur l&rsquo;activit\u00e9 humaine<\/li>\n<li>Esp\u00e8ces concern\u00e9es<\/li>\n<\/ol>\n<hr>\n<p><b>Description<\/b><\/p>\n<blockquote><p>Les pullulations de m\u00e9duses arrivent lorsque ces derni\u00e8res se reproduisent massivement et en grand nombre. La plupart des esp\u00e8ces de m\u00e9duses sont concern\u00e9es, mais certaines esp\u00e8ces sont plus enclines \u00e0 la pullulation que d&rsquo;autres.<\/p>\n<\/blockquote>\n<p>Rapidement, une m\u00eame esp\u00e8ce de m\u00e9duse (bien qu&rsquo;il peut y avoir des pullulations \u00ab mixtes \u00bb avec plusieurs esp\u00e8ces de cnidaires) peut occuper la surface et une partie de la colonne d&rsquo;eau sur plusieurs dizaines, voir plusieurs centaines de kilom\u00e8tres carr\u00e9s sur la surface de la mer.<\/p>\n<p>Les raisons de ces pullulations sont diverses :<\/p>\n<p>&#8211; R\u00e9chauffement de la temp\u00e9rature des eaux :<\/p>\n<p>Une eau d&rsquo;au moins 14 \u00b0C sera favorable \u00e0 la pullulation de m\u00e9duses. Le r\u00e9chauffement g\u00e9n\u00e9ral de l&rsquo;oc\u00e9an de 1\u00b0C a g\u00e9n\u00e9ralis\u00e9 ces pullulations. En eaux tropicales, les pullulations ont lieu toute l&rsquo;ann\u00e9e, notamment avec des esp\u00e8ces comme Linuche unguiculata, mais sont r\u00e9gul\u00e9es par des esp\u00e8ces mangeuses de m\u00e9duses.<\/p>\n<p>En milieu portuaire et au pied des rejets d&rsquo;eaux chaudes des centrales nucl\u00e9aires, les \u00e9phyrules d&rsquo;esp\u00e8ces comme Aurelia aurita peuvent bourgeonner toute l&rsquo;ann\u00e9e et sans arr\u00eat, entrainant ainsi des pullulations. Lorsque ce ph\u00e9nom\u00e8ne touche les entr\u00e9es des centrales nucl\u00e9aires, les cr\u00e9pines d&rsquo;aspiration risquent d&rsquo;\u00eatre colmat\u00e9es.<\/p>\n<p>Si le r\u00e9chauffement climatique continue, il est tr\u00e8s probable que les populations de m\u00e9duses augmenteront \u00e9norm\u00e9ment dans toutes les mers et oc\u00e9ans du monde, condamnant par ailleurs les poissons, de plus en plus mang\u00e9s et concurrenc\u00e9s par les m\u00e9duses.<\/p>\n<p>&#8211; Disparition des pr\u00e9dateurs :<\/p>\n<p>En effet, de nombreux animaux, notamment en M\u00e9diterran\u00e9e, comme les tortues marines et les thons, principaux mangeurs de m\u00e9duses, en disparaissant, favorisent les pullulations. En Espagne, on tente de r\u00e9introduire les tortues marines pour stopper les pullulations de Pelagia noctiluca. C&rsquo;est, avec le r\u00e9chauffement des eaux, une des raisons principales de la multiplication des Pelagia noctiluca en M\u00e9diterran\u00e9e du nord.<\/p>\n<p>&#8211; Disparition des poissons \u00e0 cause de la surp\u00eache :<\/p>\n<p>La niche \u00e9cologique d\u00e9laiss\u00e9e par les poissons p\u00e9lagiques est occup\u00e9e par les m\u00e9duses, qui se nourrissent de la m\u00eame nourriture (Plancton, petit necton) et occupent le m\u00eame milieu (Pleine eau). De plus, la surp\u00eache concerne aussi des pr\u00e9dateurs, comme le thon rouge, dont la disparition partielle en M\u00e9diterran\u00e9e encourage la multiplication de Pelagia noctiluca.<\/p>\n<p>&#8211; Pollution chimique :<\/p>\n<p>Cette section est vide, pas assez d\u00e9taill\u00e9e ou incompl\u00e8te. Votre aide est la bienvenue !<\/p>\n<p>Cons\u00e9quences<\/p>\n<blockquote><p>Les cons\u00e9quences de ces pullulations sont le plus souvent n\u00e9fastes, dont pour l&rsquo;homme.<\/p>\n<\/blockquote>\n<hr>\n<p><b>Cons\u00e9quences sur l&rsquo;activit\u00e9 humaine<\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ecosystemadotpro.files.wordpress.com\/2010\/06\/meduse_1.jpg\" class=\"alignnone size-full wp-image-35\" alt=\"meduse_1\" width=\"1024\" height=\"753\"><\/p>\n<p>Les pullulations de m\u00e9duses, lorsqu&rsquo;elles sont urticantes, peuvent \u00eatre n\u00e9fastes pour le tourisme : les esp\u00e8ces comme Pelagia noctiluca, notamment en M\u00e9diterran\u00e9e, sont de v\u00e9ritables plaies pour les baigneurs. De plus, lorsqu&rsquo;elles s&rsquo;\u00e9chouent, des passants peuvent \u00eatres piqu\u00e9s si ces derniers marchent dessus par accident. Les municipalit\u00e9s concern\u00e9es sont forc\u00e9es de fermer les plages, d&rsquo;installer des filets anti m\u00e9duses ou de capturer les m\u00e9duses en masse pour les incin\u00e9rer.<\/p>\n<p>Les pullulations de m\u00e9duses, lorsqu&rsquo;elles traversent des zones de pisciculture, peuvent, s&rsquo;il s&rsquo;agit d&rsquo;esp\u00e8ces relativement urticantes, tuer un grand nombre de poissons et ruiner les pisciculteurs. Un des cas les plus connus et celui de l&rsquo;invasion de Pelagia noctiluca en Irlande du nord, en mi-novembre 2007, tuant plus de 10 000 saumons et coutant plus de 2 millions de dollars.<\/p>\n<p>Les pullulations de m\u00e9duses pr\u00e8s de centrales nucl\u00e9aires ou de centre de d\u00e9salinisation de l&rsquo;eau de mer peuvent colmater les cr\u00e9pines d&rsquo;aspiration.<\/p>\n<hr>\n<p><b>Esp\u00e8ces concern\u00e9es<\/b><\/p>\n<p>Aurelia aurita, la m\u00e9duse commune, que l&rsquo;on trouve souvent en pullulation et qui est cosmopolite du monde entier. N\u00e9anmoins, elle n&rsquo;est pas dangereuse pour l&rsquo;homme et sa piq\u00fbre peut \u00eatre ressentie de diff\u00e9rentes fa\u00e7ons, de sympt\u00f4mes nuls \u00e0 une piq\u00fbre douloureuse.<\/p>\n<p>Pelagia noctiluca, qui n&rsquo;est pas dangereuse pour l&rsquo;homme, mais dont la piq\u00fbre est relativement douloureuse. Cette esp\u00e8ce est assez encline \u00e0 la pullulation, notamment en M\u00e9diterran\u00e9e o\u00f9 elle est consid\u00e9r\u00e9e comme une v\u00e9ritable plaie. D&rsquo;autres pullulations \u00e0 travers le monde de cette esp\u00e8ce ont \u00e9t\u00e9 signal\u00e9es, notamment dans l&rsquo;Atlantique, par exemple en Irlande et dans l&rsquo;Uruguay.<\/p>\n<p>Nemopilema nomurai qui est devenue invasive au Japon, o\u00f9 elle se prennent par centaines dans les filets de p\u00eache. Cette m\u00e9duse pose probl\u00e8me depuis Ao\u00fbt 2005, d\u00e9chirants les filets, \u00e9crasant et intoxiquant les poissons captur\u00e9s se trouvant en dessous d&rsquo;elle -du fait de sa masse relativement importante- faisant ainsi perdre de la valeur commerciale aux prises.<\/p>\n<p>Cyanea capillata que les p\u00eacheurs de l&rsquo;Atlantique nord prennent souvent par centaines dans leurs filets. De masse tr\u00e8s importante, elle est accus\u00e9e du m\u00eame impact sur les prises de p\u00eache que sa cousine nippone.<\/p>\n<p>Velella velella que l&rsquo;on voit souvent \u00e9chou\u00e9e sur les plages par centaines mais qui n&rsquo;est ni urticante, ni dangereuse pour l&rsquo;homme.<\/p>\n<p>Linuche unguiculata, une petite esp\u00e8ce tropicale qui souvent peut former des bandes de plusieurs milliers d&rsquo;individus, couvrant plus de 300 km2 et plusieurs m\u00e8tres de profondeur. Les piq\u00fbres ne sont pas dangereuses, mais peuvent causer, notamment par les larves et les jeunes, des \u00e9ruptions cutan\u00e9es appel\u00e9es seabather&rsquo;s eruption.<\/p>\n<blockquote><p>Et enfin <b><i>Rhizostoma pulmo et\/ou Rhizostoma octopus<\/i><\/b>, non dangereuse pour l&rsquo;homme, pas ou peu urticante, causant tout au plus des rougeurs et quelques d\u00e9mangeaisons. Toutefois, elles peuvent \u00eatre la cause de pullulations.<\/p>\n<\/blockquote>\n<hr>\n<p><b>Clich\u00e9s<\/b> :&nbsp;Gaby AR BRAZ &#8211; APN Canon G9&nbsp;&#8211; Ecosystema.fr&nbsp;\u00a9<\/p>\n<p>Dessin : Dr M. SAL\u00dbN &#8211; Oc\u00e9anopolis (BREST)<\/p>\n<hr>\n<p><b>Sources<\/b> :<\/p>\n<ul>\n<li><a href=\"http:\/\/www.bretagne-vivante.org\">http:\/\/www.bretagne-vivante.org<\/a><\/li>\n<li><a href=\"http:\/\/doris.ffessm.fr\">http:\/\/doris.ffessm.fr<\/a><\/li>\n<li><a href=\"http:\/\/fr.academic.ru\">http:\/\/fr.academic.ru<\/a>\/<\/li>\n<\/ul>\n<hr>\n<p><strong>Glossaire :<\/strong><\/p>\n<ul>\n<li>Biotope : aire g\u00e9ographique bien d\u00e9limit\u00e9s, caract\u00e9ris\u00e9e par des conditions \u00e9cologiques particuli\u00e8res (sol, climats, etc.) servant de support physique aux organismes qui constituent la bioc\u00e9nose [263]. N.B. : l&rsquo;\u00e9cosyst\u00e8me est constitu\u00e9 par l&rsquo;ensemble. biotope + bioc\u00e9nose [942].<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Voici une esp\u00e8ce observ\u00e9e dans le port de Douarnenez (29) en grand nombre. Il s&rsquo;agit de Rhizostoma pulmo (Macri, 1778) ; c&rsquo;est une \u00ab\u00a0M\u00e9duses vraies\u00a0\u00bb (Scyphozoaires) cosmopolite (Distribution Mondiale). On l&rsquo;appel aussi plus commun\u00e9ment \u00ab\u00a0Poumon de mer\u00a0\u00bb ou \u00ab\u00a0m\u00e9duse chou-fleur\u00a0\u00bb Pour l&rsquo;identifier, il s&rsquo;agit d&rsquo;une m\u00e9duse massive de grande taille (m\u00e9duse plut\u00f4t bleut\u00e9e et inoffensive),&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[102],"class_list":["post-28","post","type-post","status-publish","format-standard","hentry","category-faune-oceanographie","tag-rhizostoma-octopus"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":2,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/28\/revisions"}],"predecessor-version":[{"id":3384,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/28\/revisions\/3384"}],"wp:attachment":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/media?parent=28"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/categories?post=28"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/tags?post=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}