{"id":2225,"date":"2022-05-18T16:23:14","date_gmt":"2022-05-18T14:23:14","guid":{"rendered":"https:\/\/ecosystemadotpro.wordpress.com\/?p=2225"},"modified":"2023-06-29T17:09:09","modified_gmt":"2023-06-29T15:09:09","slug":"presentation-de-ma-demarche-de-bivouacs-naturalistes-et-gear-list-ver-10-02-ete-hiver-2022","status":"publish","type":"post","link":"https:\/\/ecosystema.fr\/index.php\/2022\/05\/18\/presentation-de-ma-demarche-de-bivouacs-naturalistes-et-gear-list-ver-10-02-ete-hiver-2022\/","title":{"rendered":"Pr\u00e9sentation de ma d\u00e9marche de \u00ab Bivouacs naturalistes \u00bb et \u00ab Gear list \u00bb ver.10.02 \u00e9t\u00e9-hiver 2022"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/ecosystema.fr\/wp-content\/uploads\/2023\/06\/31082022_glb6848-1024x681.jpg\" alt=\"\" class=\"wp-image-3361\" srcset=\"https:\/\/ecosystema.fr\/wp-content\/uploads\/2023\/06\/31082022_glb6848-1024x681.jpg 1024w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2023\/06\/31082022_glb6848-300x200.jpg 300w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2023\/06\/31082022_glb6848-768x511.jpg 768w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2023\/06\/31082022_glb6848-1536x1022.jpg 1536w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2023\/06\/31082022_glb6848-2048x1363.jpg 2048w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2023\/06\/31082022_glb6848-809x538.jpg 809w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Salutations \u00e0 toutes et tous,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voil\u00e0 mon \u00ab set up \u00bb &#8211; non fig\u00e9 &#8211; de sac, pour mes sorties naturalistes en bivouacs dans le massif Armoricain (et le planitiaire atlantique nord-ouest plus g\u00e9n\u00e9ralement).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N&rsquo;h\u00e9sitez pas \u00e0 commenter, poser des questions.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" data-id=\"2231\" src=\"https:\/\/ecosystema.fr\/wp-content\/uploads\/2022\/05\/img_0081.jpg\" alt=\"\" class=\"wp-image-2231\" srcset=\"https:\/\/ecosystema.fr\/wp-content\/uploads\/2022\/05\/img_0081.jpg 600w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2022\/05\/img_0081-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Syst\u00e8me dunaire<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"408\" data-id=\"2232\" src=\"https:\/\/ecosystema.fr\/wp-content\/uploads\/2022\/05\/ecosystema_gabydirlem_0005.jpg\" alt=\"\" class=\"wp-image-2232\" srcset=\"https:\/\/ecosystema.fr\/wp-content\/uploads\/2022\/05\/ecosystema_gabydirlem_0005.jpg 600w, https:\/\/ecosystema.fr\/wp-content\/uploads\/2022\/05\/ecosystema_gabydirlem_0005-300x204.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Sylvofaci\u00e8s caducifol\u00e9<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">Entre littoral et plaine d\u2019Europe de l\u2019ouest<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Qui suis-je ?<br>Je m&rsquo;appelle Gaby, je suis ancien militaire et suite \u00e0 un accident : \u00e9cologue naturaliste durant 25 ans. De nature passionn\u00e9e, je m\u2019int\u00e9resse pour le nature armoricaine, au point de \u00ab&nbsp;r\u00eaver&nbsp;\u00bb d&rsquo;y passer tout mon temps et pourquoi pas d\u2019y finir ma vie. Et ce, apr\u00e8s avoir fait les 4 coins du monde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai choisi de partager mes sorties en nature, mes astuces et mes revues de mat\u00e9riel pour faire petit \u00e0 petit et \u00e0 force d&rsquo;efforts, de mes partages Web, une activit\u00e9 \u00e0 plein temps. Et aussi &#8211; comme le dit ma compagne &#8211; pour me stimuler. Le prix \u00e0 payer pour un soldat ayant un genoux \u00e0 terre\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pourquoi bivouaquer ? Au XXI e si\u00e8cle ? Un besoin de d\u00e9connexion !<br>Le fait d\u2019\u00eatre tout le temps connect\u00e9 et l\u2019injonction \u00e0 la disponibilit\u00e9 permanente sont \u00e9puisants ; je l\u2019ai v\u00e9cu dans ma fuite de travail durant 25 ans d\u2019\u00e9cologue naturaliste et mes 100 h par semaine.<br>Par ailleurs, j\u2019ai honte de le dire &#8211; en tant qu\u2019ancien humanitaire &#8211; et pratiquant le m\u00e9tier d\u2019ecologue (un m\u00e9tier riche par essence), les exp\u00e9riences devenaient\u2026 banales !<br>Voyager seul permet &#8211; \u00e0 mon sens &#8211; donc d\u2019une part, de retrouver de l\u2019intensit\u00e9 ou de l\u2019authenticit\u00e9 et d\u2019autre part, de red\u00e9couvrir les vertus de l\u2019ennui. Deux id\u00e9es qui ne sont finalement peut-\u00eatre pas antinomiques !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussi et dans cet esprit, je partage sinc\u00e8rement et en toute humilit\u00e9 mes connaissances naturalistes et mon exp\u00e9rience de terrain.<br>J&rsquo;ai appris pas mal de choses de la part de personnes bienveillantes, dans la rue\u2026, sur les terrains d\u2019actions humanitaires, de missions naturalistes et autres. Je partage donc \u00e0 mon tour de fa\u00e7on g\u00e9n\u00e9reuse, car tel est mon cr\u00e9do\u2026 ma destin\u00e9e ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mon mat\u00e9riel 4 saisons (en r\u00e9alit\u00e9 2 saisons : hiver \u2744\ufe0f et \u00e9t\u00e9 \ud83c\udf24 ; les deux autres \u00e9tant des p\u00e9riodes de transition) de plaines (&lt; \u00e0 800 m) est b\u00e2ti selon le principe des 7 C (extension du dit \u00ab&nbsp;5 C&nbsp;\u00bb dans les situations de survie, voire ci-apr\u00e8s) :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Outil de Coupe,<\/li>\n\n\n\n<li>Couverture (Abri) Tout \u00e9quipement permettant de se garder \u00e0 la chaleur,<\/li>\n\n\n\n<li>Combustion (Feu) Tout item permettant d&rsquo;allumer un feu<\/li>\n\n\n\n<li>Contenant (Gestion hydrique),<\/li>\n\n\n\n<li>Cordage,<br>Et aussi :<\/li>\n\n\n\n<li>Compas (Orientation)<\/li>\n\n\n\n<li>et Communication (si appelle des secours).<\/li>\n<\/ol>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Compl\u00e8tement universelle, les cinq \u00ab C \u00bb sont : 1. \u00ab&nbsp;Cutting tools \u00bb&nbsp;: des outils coupants pour fabriquer les objets dont vous aurez besoin et pour vous occuper de la nourriture ; 2. \u00ab&nbsp;Cover elements \u00bb&nbsp;: des \u00e9l\u00e9ments couvrants pour cr\u00e9er un microclimat vous prot\u00e9geant des \u00e9l\u00e9ments naturels ; 3. \u00ab&nbsp;Combustion devices \u00bb&nbsp;: un dispositif de combustion pour faire du feu, n\u00e9cessaire non seulement pour conserver et cuire la nourriture mais aussi pour fabriquer des m\u00e9dicaments et pour obtenir de la chaleur ; 4. \u00ab&nbsp;Containers \u00bb&nbsp;: des r\u00e9cipients pour transporter de l\u2019eau sur de longues distances ou pour prot\u00e9ger les sources de nourriture collect\u00e9es ; 5. \u00ab&nbsp;Cordages \u00bb&nbsp;: des cordages pour fabriquer des liens et attacher des objets<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin un grand merci \u00e0 mon ma\u00eetre : le professeur BOULLARD, un homme o\u00f9 l\u2019\u00e9rudition et le savoir se m\u00ealaient \u00e0 la po\u00e9sie des descriptions et \u00e0 un humour de bon aloi. Et une pens\u00e9e sinc\u00e8re \u00e0 mon premier \u00ab&nbsp;patron&nbsp;\u00bb et amis : Philippe H. que la maladie a emport\u00e9e que pr\u00e9matur\u00e9ment ; un grand naturaliste Normand nous a quitt\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et merci de partager ces instant intimes avec moi, et n\u2019oubliez pas le credo du naturaliste :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>l\u2019humilit\u00e9,<\/li>\n\n\n\n<li>l&rsquo;esprit zen (et sto\u00efcisme, comme en tant que Breton, ne pas pester face aux intemp\u00e9ries \ud83d\ude2c merci au Docteur ANDR\u00c9)<\/li>\n\n\n\n<li>et comme m\u2019a enseign\u00e9 l\u2019arm\u00e9e : la rigueur<\/li>\n<\/ol>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Gaby \u00ab curieux de nature \u00bb.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">SOUTENIR LE BLOG ECOSYSTEMA \u2122\ufe0f<br>Partagez ce post (= capsule) et suivez-moi \ud83d\ude01<br>\u00ab&nbsp;L\u2019homme qui progresse \u00e0 pied, pr\u00eat \u00e0 camper n\u2019importe o\u00f9 et par n\u2019importe quel temps, est le plus ind\u00e9pendant sur terre.&nbsp;\u00bb<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">H. KEPHART, 1904<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Historique du set up :<br>Depuis quelques ann\u00e9es (2014, date de mon arr\u00eat d\u2019activit\u00e9 professionnelle pour raison de sant\u00e9) en survivant \ud83d\ude05, pour mon projet de vie pr\u00e9sent et futur, j&rsquo;exp\u00e9rimente cette liste de mat\u00e9riel pour mes sorties en milieux semi-naturels en dessous du collin\u00e9en (&lt; 800 m) &#8211; toute saison &#8211; pour les plaines de France et d\u2019Europe septentrionale (temp\u00e9ratures de gel\u00e9es rares).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9l\u00e9ments cit\u00e9s ci-apr\u00e8s sont loin d&rsquo;\u00eatre indispensables : ce sont simplement des \u00e9l\u00e9ments que j&rsquo;aime utiliser lors de mes bivouacs. Bien entendu ils \u00e9voluent entres les deux saisons : \u00e9t\u00e9, hiver et ses transitions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Liste des \u00e9l\u00e9ments &#8211; par cat\u00e9gories &#8211; pour un sac inf\u00e9rieur \u00e0 09 kg (sans le mat\u00e9riel photo, vid\u00e9o et naturaliste) pour une capacit\u00e9 de 70 litres \ud83d\ude2c.<br>Je renouvelle parfois &#8211; par curiosit\u00e9, ou n\u00e9cessit\u00e9 &#8211; mon mon mat\u00e9riel ; mais certains datent de 1990 !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voil\u00e0 la \u00ab&nbsp;Gear list&nbsp;\u00bb 1990-2022 : mais attention \u26a0\ufe0f sachez que le mat\u00e9riel est secondaire pour moi. Et cette liste est \u00e9tablie le plus sinc\u00e8rement possible, pour ne pas faire de vid\u00e9o incessante de contenu de sac. Je laisse cela d\u2019autres &#8211; bien plus au fait, du mat\u00e9riel du moment.<br>Et surtout, ayez une d\u00e9marche minimaliste de votre pratique du bivouacs \ud83d\ude05\u2026 ce qui n\u2019aura pas \u00e9t\u00e9 mon cas en 2022 \u2757\ufe0fmais cela me fait plaisir.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Poids du sac (sans les options Tentes\/T. Tunnel et Hamacs) : le poids exact sera pr\u00e9cis\u00e9 prochainement.<\/p><cite>Gaby AR BRAZ<\/cite><\/blockquote><\/figure>\n\n\n\n<pre class=\"wp-block-preformatted\">\u00ab Gear list \u00bb de bivouac naturaliste 18 mai 2022 (version 10.02) - Toutes saisons (\u00e0 adapter) - PROJET 2022<\/pre>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module PORTAGE<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00ab Rucksack \u00bb Sac \u00e0 dos Homme trekking 70 + rehausse (= capuchons) 10 L | Forclaz MT 900 SYMBIUM &#8211; Armature | \u00ab D\u00e9cathlon \u00bb &#8211; 2022 Garantie 10 ans<\/li>\n\n\n\n<li>\u00ab Rain cover \u00bb &#8211; Housse de pluie renforc\u00e9e | pour sac \u00e0 dos de trekking 70-100 L Forclaz | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>2 sangles de serrage | Forclaz 25 mm x 1 m | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>Sac de Bouteille d&rsquo;eau R\u00e9glable 300-800ml | Nylon Sac Bandouli\u00e8re Imperm\u00e9able &#8211; Molle Syst\u00e8me | \u00ab Yakmoo \u00bb<\/li>\n\n\n\n<li>Accroche sac (sur arbre) | Cordelette + mousqueton |<\/li>\n\n\n\n<li>Sac \u00e9tanche intel et papier |<\/li>\n\n\n\n<li>2 \u00ab Dry Bag \u00bb Sacs marins \u00e9tanches | 2L (91 g) 5L (205 g) | ensemble 2 unit\u00e9s randonn\u00e9e &#8211; Light fermeture roll top | \u00ab Outdoor Panda \u00bb<\/li>\n\n\n\n<li>2 Housses imperm\u00e9able de rangement de tissus | sac 70 L Forclaz &#8211; Demie-Lune 15 L fermeture roll top | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>Housse de compression trekking &#8211; v\u00eatements de nuits | Forclaz 8 L | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>Sac \u00e9tanche (alimentation) | Taille Unique 4 L 15&#215;33 cm &#8211; Cordura\u00ae &#8211; Ultralight fermeture roll top | \u00ab Sea to Summit \u00bb<\/li>\n\n\n\n<li>Sacoche \u00ab \u00e9lectronique \u00bb | Technique pouch | \u00ab Peak design \u00bb<\/li>\n\n\n\n<li>Pochette de rangement \u00ab organiser \u00bb de sac \u00e0 main mixte | type \u00ab EDC \u00bb (\u00ab que l&rsquo;on porte tous les jours \u00bb) &#8211; Beefy | Protection T\u00e9flon &#8211; Compartiment principal : 15,2 x 20,3 x 5,1 cm Ext\u00e9rieur avant : une (1) poche en maille de 14 cm (L) x 13 cm (H) | \u00ab Maxpedition Legacy series \u00bb<\/li>\n\n\n\n<li>Sac poubelle 100 L<\/li>\n\n\n\n<li>Sac photo \u00ab APRN \u00bb | Dimensions ext\u00e9rieures : 38,50 x 24,50 x 32,00 | \u00c0 l\u2019\u00e9paule grande capacit\u00e9 &#8211; Bandouli\u00e8re \u00ab Vertebral Tech \u00bb \/ Magnum 200 AW noir | \u00ab Lowepro \u00bb<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module BIVOUACS<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>[Option A] Tente d\u00f4me de trekking | Forclaz MT 900 &#8211; Double parois (Toit + Chambre), mi-autoportantes 1 place | \u00ab D\u00e9cathlon \u00bb 2022 Garantie 5 ans<\/li>\n\n\n\n<li>\u00ab Footprint \u00bb Tapis de sol ultralight pour tente | Forclaz MT 900 &#8211; montage uni-parois : montage tarp sans la chambre (temps pluvieux) | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>[Option B] Tente tunnel de trekking | ultralight raid 980 (Bivouac furtif) | \u00ab coleman \u00bb 2005<\/li>\n\n\n\n<li>\u00ab Footprint \u00bb Tapis de sol (Couverture de survie r\u00e9utilisable) | Toile 150 x 210 cm, \u00e9tanche, ultra l\u00e9g\u00e8re, r\u00e9utilisable, isolation thermique, pliable | \u00ab Bearhard \u00bb 3.0<\/li>\n\n\n\n<li>[Option C1] Tarp (= b\u00e2che) \u00ab Bushcraft \u00bb 2,97 x 2,85 imperm\u00e9able 26 points &#8211; Camouflage \u00ab Furtiv \u00bb Solognac | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>[Option C2] Hamac \u00ab Bushcraft \u00bb r\u00e9sistant Ripstop &#8211; 1 personne &#8211; Camouflage \u00ab Furtiv \u00bb Solognac | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>10 piquets de tente \u00e9troits | Forclaz MT 900 | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>8 piquets de tente larges | titane ultra l\u00e9gers en forme de V | \u00ab iBasingo \u00bb<\/li>\n\n\n\n<li>Sac r\u00e9parations (Tentes, Sacs, Chaussures, gourde, couture, divers)<\/li>\n\n\n\n<li>Lampe frontale | Forclaz Trek 100 USB (IPX 4) | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>Sandales de bivouacs | Forclaz T 45 (pied droit) | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>Matelas mousse de trekking pliable isolant | Forclaz MT 500 (RValue 2,6) 1950 x 550 | \u00ab D\u00e9cathlon \u00bb 2022 Garantie 10 ans<\/li>\n\n\n\n<li>\u00ab Liner \u00bb 3 &#8211; saisons Drap de sac \u00ab ou sac \u00e0 viande \u00bb | Trekking Forclaz MT 500 Soie &#8211; 100% de soie sans colorants &#8211; \u00e9t\u00e9 | \u00ab  D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>\u00ab Liner \u00bb hiver &#8211; Drap de sac \u00ab ou sac \u00e0 viande \u00bb | Trekking Forclaz MT 500 M\u00e9rinos &#8211; 89% de laine sans colorants &#8211; hiver | \u00ab  D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>V\u00eatements de nuits haut Couche 1 | Manches longues Laine m\u00e9rinos de trekking sans colorants Forclaz MT 500 &#8211; 86% de laine sans colorants 2XL | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>V\u00eatements de nuits haut C2 Polaire | fine &#8211; Quechua MH 500 Temp\u00e9rature de confort de 7 \u00e0 10\u00b0C sans veste suppl\u00e9mentaire 2XL | \u00ab D\u00e9cathlon <\/li>\n\n\n\n<li>V\u00eatements de nuits bas Couche 1 Xxx | Forclaz | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>V\u00eatements de nuits Tour de cou type \u00ab Buff\u00ae \u00bb | Laine m\u00e9rinos (89 %) de trekking Forclaz MT500 | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>V\u00eatements de nuits Bonnet | Laine m\u00e9rinos (89 %) de trekking Forclaz MT500 | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>V\u00eatements de nuits chaussettes | Laine m\u00e9rinos (75%) 0\u00b0 en statique &#8211; chasse Solognac STAT900 H | \u00ab D\u00e9cathlon \u00bb 44-46<\/li>\n\n\n\n<li>V\u00eatements de nuits gants | Laine m\u00e9rinos Forclaz | \u00ab D\u00e9cathlon \u00bb 2XL-XL<\/li>\n\n\n\n<li>Sac de couchage \u00e9t\u00e9 | Polyester de trekking Extr\u00eame 600 &#8211; confort 16\u00b0 (risque 13\u00b0) | \u00ab Lafuma \u00bb<\/li>\n\n\n\n<li>Sac de couchage 4 Saisons (en plaine hors collin\u00e9en) | duvet de trekking Forclaz MT 900 XL &#8211; confort 0\u00b0 &#8211; 90 % duvet et 10% plumes canard gris | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>\u00ab Pillow \u00bb Oreiller de trek | Forclaz | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>V\u00eatements de soir\u00e9es et\/ou nuits haut C3 Doudoune | synth\u00e9tique de trekking montagne Forclaz MT50 Temp\u00e9rature de confort de +10\u00b0 en statique | \u00ab D\u00e9cathlon \u00bb 2XL<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module HYDRATATION<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Flasque filtre \u00e0 eau 1L | Befree | \u00ab Katadyn \u00bb<\/li>\n\n\n\n<li>2 Bouteilles de Boisson \u201csimplBottle\u201c | 1000 mL Gourde \u00c9tanche \u00e0 col Large &#8211; gradu\u00e9e &#8211; sans BPA en copolyester Tritan\u00ae | \u00ab 720\u00b0DGREE \u00bb<\/li>\n\n\n\n<li>1 Gourde, Bouteille d\u2019Eau \u201cuberBottle\u201c + Fruit-Infuseur | 500 mL, \u00c9tanche, Anti-Fuite &#8211; sans BPA en copolyester Tritan\u00ae | \u00ab 720\u00b0DGREE \u00bb<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module CUISINE<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mini R\u00e9chaud l\u00e9ger, Poche | Po\u00eale \u00e0 Gaz Compact Portable | \u00ab Primus \u00bb<\/li>\n\n\n\n<li>Adaptateur de cartouche | pour les cartouches de connexion Campingaz CV sur Po\u00eales \u00e0 filetage \u00e0 vis | \u00ab Jeebel \u00bb<\/li>\n\n\n\n<li>Cartouche de gaz | Power Gas 4 saisons avec valve de s\u00e9curit\u00e9. (230 g de gaz sur 390 g) 3\/4 j d\u2019autonomie | \u00ab Primus \u00bb<\/li>\n\n\n\n<li>Support de cartouche de Gaz Pliant | \u00ab Alomejor \u00bb<\/li>\n\n\n\n<li>Pare vent pliable pour r\u00e9chaud de trekking | Forclaz MT 500 | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>Popote titane | Pot with Pan 1100 mL | \u00ab TOAKS \u00bb <\/li>\n\n\n\n<li>Tasse titane type \u00ab quart \u00bb 300 mL | \u00ab Ti-Time \u00bb<\/li>\n\n\n\n<li>Tasse pliante en plastique | Foldacup\u00ae original BIG 600 mL vert olive &#8211; sans BPA | \u00ab Wildo \u00bb<\/li>\n\n\n\n<li>Couteau \u00ab Jackknives \u00bb repliables \u00e9mouture plate &#8211; K9 Kattegat, Couteau de poche tranchant &#8211; avec lame en acier inoxydable noir | \u00ab BERGKVIST \u00bb <\/li>\n\n\n\n<li>Couverts titane | CCF | \u00ab Ti-Time \u00bb <\/li>\n\n\n\n<li>Ensemble de bo\u00eetes de conserve \u00ab Set of Cans \u00bb 6 PI\u00c8CES &#8211; 2&#215;60 mL, 2&#215;30 mL, 1&#215;30 mL gradu\u00e9, 1&#215;15 mL &#8211; Polycarbonate ; Poly\u00e9thyl\u00e8ne | \u00ab NALGENE\u00ae \u00bb<\/li>\n\n\n\n<li>\u00ab Flask \u00bb Flacon \u00e0 alcool &#8211; 375 mL &#8211; Polycarbonate, PET (polyethylene terephthalate) | \u00ab NALGENE\u00ae \u00bb<\/li>\n\n\n\n<li>Chiffon micro fibre multi-usages | 32&#215;32 | \u00ab Super U \u00bb<\/li>\n\n\n\n<li>Tampon \u00e0 r\u00e9curer<\/li>\n\n\n\n<li>Sacs \u00ab Ziploc \u00bb Zipper\u00ae | 20 x 15 &#8211; 1 L \u00ab Albal \u00bb<\/li>\n\n\n\n<li>Sacs Cong\u00e9lation avec liens | 18 x 25<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module orientation<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Porte carte topographique papier + boussole | \u00ab Lafuma \u00bb<\/li>\n\n\n\n<li>Boussole \u00e0 bo\u00eetier | \u00ab Recta \u00bb<\/li>\n\n\n\n<li>Altim\u00e8tre \/ Thermom\u00e8tre \/ Barom\u00e8tre \/ An\u00e9mom\u00e8tre | \u00ab Silva \u00bb alba Windwatch + pile Energizer CR 2032 3 V<\/li>\n\n\n\n<li>Cartes g\u00e9ographiques papier | Topo 25 000e | \u00ab IGN \u00bb<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module Option \u00ab art des bois \u00bb<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Couteau \u00ab Bushcraft \u00bb \u00e9mouture bomb\u00e9e Mora Companion MG Noir\/Kaki, Couteau ultra r\u00e9sistant &#8211; avec lame en acier inoxydable noir 10,5 cm | Pour b\u00e2tonnage | \u00ab MORAKNIV \u00bb<\/li>\n\n\n\n<li>Scie pliante \u00ab Bushcraft \u00bb | professionnelle \u00e0 grandes dents &#8211; 130 mm &#8211; Curve 726-13 | \u00ab PocketBoy \u00bb<\/li>\n\n\n\n<li>Bouffadou | fabrication personnelle<\/li>\n\n\n\n<li>Module type \u00ab EDC \u00bb 2022 (cf. ci-apr\u00e8s)<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module HYGIENE ET SECURITE<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kit m\u00e9dical compact | POCHETTE TRAUMAPOUCH 2.0 | \u00ab [SOLUTIONS] TRAUMAT + \u00bb<\/li>\n\n\n\n<li>Trousse de secours \u00ab San \u00bb &#8211; Grande autonomie &#8211; (vide : 142 g) &#8211; Aptonia | \u00ab D\u00e9cathlon \u00bb (cf. Liste) + Contenu MAJ 2022<\/li>\n\n\n\n<li>Multitool de Poche Suisse | Swiss Card, Taille de La Carte de Cr\u00e9dit, 10 Fonctions, Stylo, Ciseaux, Rouge Transparent | \u00ab Victorinox<\/li>\n\n\n\n<li>Trousse de toilette (vide : 43 g) | trekking pliable &#8211; Ultra Light Forclaz | \u00ab D\u00e9cathlon \u00bb (cf. Liste)<\/li>\n\n\n\n<li>Piluliers (vide) | Bo\u00eete de p\u00eache reverse 500 # sx &#8211; Caperlan | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>Serviette de bain micro fibre &#8211; L 60&#215;120 | \u00ab Nature &amp; d\u00e9couverte \u00bb<\/li>\n\n\n\n<li>Truelle \u00ab Leave No Trace \u00bb | ultral\u00e9g\u00e8re aluminium 7075-T6 de qualit\u00e9 a\u00e9rospatiale | \u00ab TheTentLab \u00bb<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module FOND DE SAC &#8211; Beefy | Maxpedition Legacy series \u00bb (vide : 166 g)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Brassard r\u00e9tro r\u00e9fl\u00e9chissant + Fluorescent Ajustable et \u00e9lastique &#8211; pour pi\u00e9ton, Jaune Fluo | \u00ab VFLUO ARMTECH \u00bb<\/li>\n\n\n\n<li>Ponchos de survie | Ultra l\u00e9gers et imperm\u00e9ables &#8211; Avec capuche &#8211; Pour les situations d&rsquo;urgence | \u00ab Bearhard \u00bb<\/li>\n\n\n\n<li>Couverture de survie<\/li>\n\n\n\n<li>Sifflet de Secours en Titane Ultra-Light avec Cordon de Survie | \u00ab Lixada \u00bb<\/li>\n\n\n\n<li>Paracorde | 30 M\u00e8tres De Haute Qualit\u00e9 &#8211; Corde de Parachute 4mm Type III \u00e0 7 Brins = Drisse lov\u00e9e pour \u00ab corde fa\u00eeti\u00e8re \u00bb de montage tarp) | \u00ab FuckTheFear \u00bb 550<\/li>\n\n\n\n<li>Paire de lunettes de vue de secours + \u00e9tui de protection<\/li>\n\n\n\n<li>Lampe LED d\u2019appoint | solitaire 47 lumens | \u00ab Maglite \u00bb<\/li>\n\n\n\n<li>2 Piles LR03 Size AAA OPTIMUM |\u00ab Duracell \u00bb<\/li>\n\n\n\n<li>Couteau pliant de poche en acier inoxydable | 8,5 cm avec d\u00e9manilleur &#8211; Manche en polym\u00e8re \u00ab Waterproof \u00bb &#8211; Sifflet inclus | \u00ab OPINEL &#8211; N\u00b008 \u00bb<\/li>\n\n\n\n<li>Couteau de Poche Suisse | Waiter, L\u00e9ger, Multitool, 9 Fonctions, Ouvre Boite, Tire Bouchon | \u00ab Victorinox \u00bb <\/li>\n\n\n\n<li>Pierre \u00e0 affuter | Pierre naturelle de gr\u00e8s des Pyr\u00e9n\u00e9es 800\/1200 de poche &#8211; Fabrication artisanale fran\u00e7aise &#8211; 120 mm | \u00ab l\u2019Ari\u00e9geoise \u00bb<\/li>\n\n\n\n<li>\u00ab Firesteel \u00bb tendre &#8211; \u00ab Pierre \u00bb allume feu en alliage m\u00e9tallique artificiel de ferroc\u00e9rium | Bear Grylls Survival Series | \u00ab Gerber \u00bb<\/li>\n\n\n\n<li>A Bo\u00eete \u00e0 feu (vide) Bo\u00eete en fer-blanc, 100% sans plastique, en mat\u00e9riau recyclable &#8211; 110 x 88 x 32,5 mm | Hydrophil<\/li>\n\n\n\n<li>A1 Kit feu | Laines feu de camp | \u00ab Feniks \u00bb<\/li>\n\n\n\n<li>A2 Bois gras de Pinus sp., cire &amp; coton, etc, \u00e9corces de B\u00e9tulac\u00e9e\u2026<\/li>\n\n\n\n<li>Briquet temp\u00eate classique | \u00ab Zippo \u00bb<\/li>\n\n\n\n<li>Flacon 12 mL essence Premium Lighter Fluid | \u00ab Zippo \u00bb<\/li>\n\n\n\n<li>Briquet \u00e0 ferroc\u00e9rium (= \u00ab pierre \u00bb) maxi + 3 000 allumages | \u00ab Bic \u00bb<\/li>\n\n\n\n<li>12 allumettes temp\u00eate | fabrication suisse | \u00ab Miltec \u00bb<\/li>\n\n\n\n<li>\u00ab Duct tape \u00bb ruban adh\u00e9sif toil\u00e9 Blazer Haute Performance, 25 mm Noir | Confortable haute performance | \u00ab 3M \u00bb<\/li>\n\n\n\n<li>\u00ab Gaffer Duct Tape \u00bb ruban adh\u00e9sif toil\u00e9 Am\u00e9ricain 50mm &#8211; \u00c9tanche extra fort pour r\u00e9parations fixation regroupement int\u00e9rieur et ext\u00e9rieur photo et vid\u00e9o | \u00ab Sanojtape \u00bb<\/li>\n\n\n\n<li>1 Sac poubelle 100 litres<\/li>\n\n\n\n<li>2 Sacs \u00ab Ziploc \u00bb Zipper\u00ae | 20 x 15 &#8211; 1 L \u00ab Albal \u00bb<\/li>\n\n\n\n<li>Soin des l\u00e8vres | Pro intense 99 % naturel 4 g | Laino<\/li>\n\n\n\n<li>Coupe-Ongles | \u00ab Victorinox \u00bb Acier Inoxydable &#8211; \u0152illet de Fixation), Rouge<\/li>\n\n\n\n<li>Mouchoirs papier de poche<\/li>\n\n\n\n<li>Marqueur Permanent | Pointe Double Noir | \u00ab Sharpie \u00bb <\/li>\n\n\n\n<li>Crayon 4 Couleurs 3 +1 HB | Stylo-Bille R\u00e9tractable et Porte-Mines | \u00ab Bic \u00bb<\/li>\n\n\n\n<li>Carnet de notes 128 p. 7,5 x 12 cm | \u00ab Clairefontaine \u00bb<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">VETEMENTS PORT\u00c9S Hiver &amp; \u00c9t\u00e9 en plaine atlantique (&lt; 800 m alt.)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Coupe-vent &#8211; \u00ab D\u00e9perlant hard shell \u00bb | \u00ab The North Face\u00ae \u00bb HyVent<\/li>\n\n\n\n<li>3-en-1 Poncho Multi-Fonctionnel Imperm\u00e9able | Cape-Poncho, Parasol, Tapis de Sol &#8211; avec \u0153illets &#8211; 217 x 143 cm en Polyester | \u00ab SaphiRose \u00bb<\/li>\n\n\n\n<li>Paire de chaussures marche | Tige moyenne \u00ab Mid \u00bb en cuir &#8211; imperm\u00e9able Novadry\u00ae Trek 100 H (45 pied droit &#8211; 1206 g) | \u00ab D\u00e9cathlon \u00bb 2022 Garantie 2 ans<\/li>\n\n\n\n<li>Semelle 45 |<\/li>\n\n\n\n<li>2 Paires de chaussettes | Marche toutes saisons &#8211;<\/li>\n\n\n\n<li>Moufles-mitaines chasse Kaki | Thinsulate\u00ae \u00ab 3M \u00bb<\/li>\n\n\n\n<li>[Option sous couche] Sous-Bonnet Hiver\/\u00c9t\u00e9 | polyamide et \u00e9lasthanne | membrane Windstopper\u00ae con\u00e7us pour vous prot\u00e9ger dans des conditions climatiques vari\u00e9es, quel que soit le type d\u2019effort. Vous pouvez vous concentrer sur votre activit\u00e9 sans \u00eatre g\u00ean\u00e9 par le froid, l\u2019humidit\u00e9 ou l\u2019exc\u00e8s de chaleur.<\/li>\n\n\n\n<li>[Option chaleur et fort soleil] Bob Australien | \u00c9t\u00e9 &#8211; Coton | Outdoor \u00ab Bushline \u00bb<\/li>\n\n\n\n<li>[Option chaleur] Casquette cache nuque Hunter | Printemps &#8211; textiles techniques Colamtex (Polyester &amp; Coton) imperm\u00e9able<\/li>\n\n\n\n<li>[Option pluie] Bob Hunter | Hiver &#8211; textiles techniques Colamtex (Polyester &amp; Coton) | \u00ab Colamtiss \u00bb imperm\u00e9able<\/li>\n\n\n\n<li>[Option froid] Bonnet Kaki | Thinsulate\u00ae \u00ab 3M \u00bb<\/li>\n\n\n\n<li>[Option toute saison sans pluie] Casquette polaire Hiver\/Et\u00e9 \u00ab Think Pink\u00ae \u00bb<\/li>\n\n\n\n<li>Echarpe Kaki Laine polaire | Polartec\u00ae \u00ab Cairn \u00bb<\/li>\n\n\n\n<li>Gu\u00eatres | supertrac 500 v2 Solognac | \u00ab D\u00e9cathlon \u00bb<\/li>\n\n\n\n<li>Ceinture Tactique | Haute Performance, Sangle en Nylon et Boucle m\u00e9tallique \u00e0 Fermeture Rapide | \u00ab BESTKEE \u00bb<\/li>\n\n\n\n<li>Moustiquaire de t\u00eate<\/li>\n\n\n\n<li>1 B\u00e2ton ultra compact de trekking | Forclaz MT 500 | \u00ab D\u00e9cathlon \u00bb (270 g)<\/li>\n\n\n\n<li>1 \u00ab P\u00f4le tips \u00bb Embout de b\u00e2ton | Forclaz \u00ab D\u00e9cathlon \u00bb (11 g)<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">NATURALISME &amp; AUTRES<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Livres naturalistes (2 vol. de Provost)<\/li>\n\n\n\n<li>Kindle 10e g\u00e9n\u00e9ration<\/li>\n\n\n\n<li>Filet \u00e0 papillons, fauchoir..<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Module DIVERS<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00ab Seat Pad \u00bb &#8211; Coussin d\u2019assise en mousse isolante &#8211; Forclaz MT 500 | \u00ab D\u00e9cathlon \u00bb<\/li>\n<\/ul>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">PHOTOGRAPHIE, VID\u00c9O &amp; ELECTRONIQUE<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bo\u00eetier \u00ab Nikon \u00bb D700 nu (avec poign\u00e9e et 2 batteries EN-EL3E)<\/li>\n\n\n\n<li>Objectif \u00ab Nikon \u00bb macro 60 mm f\/ 2.8<\/li>\n\n\n\n<li>Objectif \u00ab Nikon \u00bb 28 mm f\/ 2.8<\/li>\n\n\n\n<li>Objectif \u00ab Nikon \u00bb 50 mm f\/ 1.4<\/li>\n\n\n\n<li>Tr\u00e9pied \u00ab Joby \u00bb | 3k stand + Mini rotule tr\u00e9pied ball &amp; Griffe \u00ab Manfrotto \u00bb | Pieds \u00ab gorillapod \u00bb<\/li>\n\n\n\n<li>T\u00e9l\u00e9commande Filaire Nikon MC-36 | Nikon<\/li>\n\n\n\n<li>Plateau compl\u00e9mentaire Mini rotule tr\u00e9pied ball &amp; Griffe | \u00ab Manfrotto \u00bb<\/li>\n\n\n\n<li>Batterie \u00ab Patona \u00bb | EN-EL3E pour Nikon D700<\/li>\n\n\n\n<li>Divers (Filtres, \u2026)<\/li>\n\n\n\n<li>Cam\u00e9ra vid\u00e9o ONE RS &#8211; 4K \u00e9dition | \u00ab Insta360 \u00bb [en projet pour janvier 2023]<\/li>\n\n\n\n<li>iPod touch 7e g\u00e9n\u00e9ration : Saisie des donn\u00e9es F&amp;F + Photos | \u00ab Apple \u00bb<\/li>\n\n\n\n<li>Dictaphone | Voicetracer 860 | + 2 LR03 Size AAA OPTIMUM | \u00ab Philips \u00bb \/ Duracell<\/li>\n\n\n\n<li>Powerbank 10 050 mAh, Batterie Externe avec USB C + Charge Rapide IN\/OUT (Power Delivery 18W et Quick Charge 3.0) | \u00ab Duracell \u00bb<\/li>\n\n\n\n<li>Chargeur Prise USB Secteur &#8211; 2-Pack 2.1A 5V 2 Ports Adaptateur Alimentation Universel LED Garantie 1 ans | \u00ab LUOATIP \u00bb<\/li>\n\n\n\n<li>Cable de charge long universel | multi 3 en 1 adaptateur triple tress\u00e9 en nylon 3M &#8211; Lightning + USB C + Micro USB | \u00ab MTAKY \u00bb<\/li>\n\n\n\n<li>Carte microSD | HC 32 Go High-Speed + adaptateur USB | \u00ab Lexar \u00bb<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CC<\/strong> BY-NC-ND<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salutations \u00e0 toutes et tous, Voil\u00e0 mon \u00ab set up \u00bb &#8211; non fig\u00e9 &#8211; de sac, pour mes sorties naturalistes en bivouacs dans le massif Armoricain (et le planitiaire atlantique nord-ouest plus g\u00e9n\u00e9ralement). N&rsquo;h\u00e9sitez pas \u00e0 commenter, poser des questions. Qui suis-je ?Je m&rsquo;appelle Gaby, je suis ancien militaire et suite \u00e0 un accident&hellip;<\/p>\n","protected":false},"author":1,"featured_media":3361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,34,5,8,9,10,26,38,32],"tags":[45,52,66,67,72,84,87,98],"class_list":["post-2225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-des-bois-bushcraft","category-bivouac-naturaliste","category-bretagne","category-culture","category-ecologie","category-environnementalisme","category-massif-armoricain","category-trekking","category-voyage","tag-bivouacs","tag-bushcraft","tag-faune-entomologie","tag-faune-avisme","tag-gear-list","tag-liste-materiel","tag-naturalisme","tag-randonnee"],"jetpack_featured_media_url":"https:\/\/ecosystema.fr\/wp-content\/uploads\/2023\/06\/31082022_glb6848-scaled.jpg","_links":{"self":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/2225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2225"}],"version-history":[{"count":5,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/2225\/revisions"}],"predecessor-version":[{"id":3510,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/posts\/2225\/revisions\/3510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/media\/3361"}],"wp:attachment":[{"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecosystema.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}